{"id":57,"count":8,"description":"","link":"https:\/\/dsc-preussen.de\/hockey\/category\/vorstand\/","name":"Vorstand","slug":"vorstand","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/dsc-preussen.de\/hockey\/wp-json\/wp\/v2\/categories\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dsc-preussen.de\/hockey\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dsc-preussen.de\/hockey\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dsc-preussen.de\/hockey\/wp-json\/wp\/v2\/posts?categories=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}